{"id":335,"date":"2026-04-13T14:08:18","date_gmt":"2026-04-13T14:08:18","guid":{"rendered":"https:\/\/thekropak.com\/sidemen\/?page_id=335"},"modified":"2026-08-23T15:05:58","modified_gmt":"2026-08-23T15:05:58","slug":"facilities","status":"publish","type":"page","link":"https:\/\/thekropak.com\/sidemen\/facilities\/","title":{"rendered":"Facilities"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"335\" class=\"elementor elementor-335\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e8aad7 e-flex e-con-boxed e-con e-parent\" data-id=\"0e8aad7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1231,&quot;url&quot;:&quot;https:\\\/\\\/thekropak.com\\\/sidemen\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/endek1.webp&quot;},{&quot;id&quot;:1228,&quot;url&quot;:&quot;https:\\\/\\\/thekropak.com\\\/sidemen\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/songket12.webp&quot;},{&quot;id&quot;:1227,&quot;url&quot;:&quot;https:\\\/\\\/thekropak.com\\\/sidemen\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/songket11.webp&quot;},{&quot;id&quot;:1234,&quot;url&quot;:&quot;https:\\\/\\\/thekropak.com\\\/sidemen\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/endek4.webp&quot;},{&quot;id&quot;:1248,&quot;url&quot;:&quot;https:\\\/\\\/thekropak.com\\\/sidemen\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/gringsing8.webp&quot;},{&quot;id&quot;:1232,&quot;url&quot;:&quot;https:\\\/\\\/thekropak.com\\\/sidemen\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/endek2.webp&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-880f3f4 e-con-full e-flex e-con e-child\" data-id=\"880f3f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21882cd elementor-widget elementor-widget-heading\" data-id=\"21882cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Facilities<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-511c45e elementor-widget elementor-widget-heading\" data-id=\"511c45e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">where comfort meets nature<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2afe9c9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2afe9c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#learn-more\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-chevron-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0a59c7 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"e0a59c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70a0aef elementor-widget__width-initial elementor-absolute elementor-hidden-mobile dce_masking-none elementor-widget elementor-widget-image\" data-id=\"70a0aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"864\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_02.webp\" class=\"attachment-full size-full wp-image-1547\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_02.webp 864w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_02-240x300.webp 240w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_02-819x1024.webp 819w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_02-768x960.webp 768w\" sizes=\"(max-width: 864px) 100vw, 864px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ead4193 e-con-full e-flex e-con e-child\" data-id=\"ead4193\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-014eb10 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"014eb10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb1fdb1 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"fb1fdb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket13.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"songket3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIyOSwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9zb25na2V0MTMud2VicCJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket13.webp\" class=\"attachment-full size-full wp-image-1229\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket13.webp 720w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket13-200x300.webp 200w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket13-683x1024.webp 683w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de8ade7 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"de8ade7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6a7111 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"b6a7111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket3.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"songket12\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIxOSwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9zb25na2V0My53ZWJwIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket3.webp\" class=\"attachment-full size-full wp-image-1219\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket3.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket3-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket3-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket3-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket3-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c84de9 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"8c84de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket8.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"songket8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIyNCwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9zb25na2V0OC53ZWJwIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket8.webp\" class=\"attachment-full size-full wp-image-1224\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket8.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket8-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket8-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket8-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket8-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e00ca3 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"9e00ca3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-301f8b6 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"301f8b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing1.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"gringsing1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI0MSwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9ncmluZ3NpbmcxLndlYnAifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing1.webp\" class=\"attachment-full size-full wp-image-1241\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing1.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing1-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing1-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing1-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing1-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c221fba dce_masking-none elementor-widget elementor-widget-image\" data-id=\"c221fba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Songket Motif_01\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NiwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA3XC9Tb25na2V0LU1vdGlmXzAxLndlYnAifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"864\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01.webp\" class=\"attachment-full size-full wp-image-1546\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01.webp 864w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01-240x300.webp 240w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01-819x1024.webp 819w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01-768x960.webp 768w\" sizes=\"(max-width: 864px) 100vw, 864px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9a74d8 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"a9a74d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-084a395 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"084a395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek3.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"endek3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzMywidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9lbmRlazMud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek3.webp\" class=\"attachment-full size-full wp-image-1233\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek3.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek3-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek3-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek3-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek3-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75ea5ee dce_masking-none elementor-widget elementor-widget-image\" data-id=\"75ea5ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing8.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"gringsing8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI0OCwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9ncmluZ3Npbmc4LndlYnAifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing8.webp\" class=\"attachment-full size-full wp-image-1248\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing8.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing8-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing8-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing8-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/gringsing8-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-278135d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"278135d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek4.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"endek4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzNCwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9lbmRlazQud2VicCJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek4.webp\" class=\"attachment-full size-full wp-image-1234\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek4.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek4-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek4-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek4-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/endek4-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a34019 e-con-full learn-more e-flex e-con e-parent\" data-id=\"5a34019\" data-element_type=\"container\" data-e-type=\"container\" id=\"learn-more\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-187331b e-flex e-con-boxed e-con e-child\" data-id=\"187331b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a722f5e e-con-full e-flex e-con e-child\" data-id=\"a722f5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6829a5d elementor-widget elementor-widget-heading\" data-id=\"6829a5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cempala kitchen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7992aa6 elementor-widget elementor-widget-text-editor\" data-id=\"7992aa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nestled within the peaceful surroundings of The Kropak Sidemen, Cempala Kitchen offers a dining experience inspired by the richness of Balinese flavors and the beauty of nature. We celebrate locally sourced ingredients, seasonal flavors, and traditional recipes with a contemporary touch. Every dining experience is designed to nourish both body and soul.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e55e0b elementor-widget elementor-widget-text-editor\" data-id=\"8e55e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dining Experiences:<\/p><ul><li>Romantic Dinner<\/li><li>Traditional Cooking Experience by Our Cooking Class<\/li><li>Floating Breakfast<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-background-color=\"#FFFFFF00\" class=\"elementor-element elementor-element-c09ca08 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c09ca08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/thekropak.com\/sidemen\/facilities\/#gallery\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">explore more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c32eac e-con-full e-flex e-con e-child\" data-id=\"7c32eac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-337cee1 elementor-widget__width-initial elementor-absolute dce_masking-none elementor-widget elementor-widget-image\" data-id=\"337cee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/elementor\/thumbs\/CEMPALA-KITCHEN-scaled-rpofi5cfrxbbote7t76t2oewsr2o5xsprj1sor83ss.webp\" title=\"CEMPALA KITCHEN\" alt=\"CEMPALA KITCHEN\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd3744d elementor-widget__width-inherit dce_masking-none elementor-widget elementor-widget-image\" data-id=\"dd3744d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/DVN00471.webp\" class=\"attachment-full size-full wp-image-1597\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/DVN00471.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/DVN00471-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/DVN00471-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/DVN00471-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/DVN00471-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cff5cec elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-child\" data-id=\"cff5cec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0f89cc7 e-con-full e-flex e-con e-child\" data-id=\"0f89cc7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20c700f elementor-widget__width-inherit dce_masking-none elementor-widget elementor-widget-image\" data-id=\"20c700f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/02\/lo28.jpg\" class=\"attachment-full size-full wp-image-65\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/02\/lo28.jpg 1600w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/02\/lo28-300x169.jpg 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/02\/lo28-1024x576.jpg 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/02\/lo28-768x432.jpg 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/02\/lo28-1536x864.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe65618 elementor-widget__width-initial elementor-absolute dce_masking-none elementor-widget elementor-widget-image\" data-id=\"fe65618\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/elementor\/thumbs\/siddhi-wellness-rpog21lgfojtfohtmssiuno5gd0d3as6i05sdlq43g.webp\" title=\"siddhi wellness\" alt=\"siddhi wellness\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34dd385 e-con-full e-flex e-con e-child\" data-id=\"34dd385\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f53bde8 elementor-widget elementor-widget-heading\" data-id=\"f53bde8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Siddhi Wellness<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b85d629 elementor-widget elementor-widget-text-editor\" data-id=\"b85d629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Siddhi Wellness is a premier holistic sanctuary where ancient healing wisdom meets modern science. Designed to help you restore balance and achieve your highest potential, our tranquil facilities offer a curated blend of personalized body therapies, mindfulness practices, and state-of-the-art recovery treatments. Whether you are seeking relief from daily stress, deep physical restoration, or a dedicated space for self-care, Siddhi Wellness provides the expert guidance and environment you need to truly thrive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c596c2d elementor-widget elementor-widget-text-editor\" data-id=\"c596c2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wellness Experiences:<\/p><ul><li>Mind &amp; Body<\/li><li>Healing Rituals<\/li><li>Wellness Lifestyle<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63abf1a e-flex e-con-boxed e-con e-child\" data-id=\"63abf1a\" data-element_type=\"container\" data-e-type=\"container\" id=\"art\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e897b2d e-con-full e-flex e-con e-child\" data-id=\"e897b2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-509e27a elementor-widget__width-inherit dce_masking-none elementor-widget elementor-widget-image\" data-id=\"509e27a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket12.webp\" class=\"attachment-full size-full wp-image-1228\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket12.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket12-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket12-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket12-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/04\/songket12-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f240746 e-con-full e-flex e-con e-child\" data-id=\"f240746\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c7de84 elementor-widget elementor-widget-heading\" data-id=\"6c7de84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The art of sidemen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01b178d elementor-widget elementor-widget-text-editor\" data-id=\"01b178d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Discover the timeless beauty of Sidemen through its traditions, craftsmanship, and way of life. Rooted in nature and shaped by generations of local artisans, every story reflects the authentic spirit of a village where culture continues to thrive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-857698a elementor-widget__width-initial elementor-absolute dce_masking-none elementor-widget elementor-widget-image\" data-id=\"857698a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"864\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01.webp\" class=\"attachment-full size-full wp-image-1546\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01.webp 864w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01-240x300.webp 240w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01-819x1024.webp 819w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/07\/Songket-Motif_01-768x960.webp 768w\" sizes=\"(max-width: 864px) 100vw, 864px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aed9b98 e-flex e-con-boxed e-con e-parent\" data-id=\"aed9b98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2c4fa90 e-con-full e-flex e-con e-child\" data-id=\"2c4fa90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c11005a elementor-widget elementor-widget-heading\" data-id=\"c11005a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The weaving heritage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06a95d5 elementor-widget elementor-widget-text-editor\" data-id=\"06a95d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>From the elegance of Songket to the sacred Gringsing and the timeless Endek, each textile tells a story of artistry, identity, and cultural heritage that continues to inspire our spaces.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-887da1a e-grid e-con-full e-con e-child\" data-id=\"887da1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2727974 e-con-full e-flex e-con e-child\" data-id=\"2727974\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-c2c8da3 elementor-widget elementor-widget-heading\" data-id=\"c2c8da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Songket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3037f01 elementor-widget elementor-widget-text-editor\" data-id=\"3037f01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A symbol of elegance and celebration, Songket is a traditional handwoven textile crafted with intricate patterns and metallic threads. It reflects the richness of Balinese artistry and the timeless beauty of cultural heritage<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82c9646 e-con-full e-flex e-con e-child\" data-id=\"82c9646\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-ea662d6 elementor-widget elementor-widget-heading\" data-id=\"ea662d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gringsing<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5af1ef elementor-widget elementor-widget-text-editor\" data-id=\"e5af1ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Known as one of Bali\u2019s most sacred textiles, Gringsing represents harmony, protection, and balance. Handwoven using a rare double ikat technique, it embodies centuries of tradition and spiritual significance<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0897270 e-con-full e-flex e-con e-child\" data-id=\"0897270\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-fba1818 elementor-widget elementor-widget-heading\" data-id=\"fba1818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Endek<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91b3f4e elementor-widget elementor-widget-text-editor\" data-id=\"91b3f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Endek is an iconic Balinese woven fabric that celebrates creativity and everyday cultural expression. With its distinctive patterns and vibrant character, it reflects the warmth, craftsmanship, and living traditions of Bali<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17e3256 elementor-widget elementor-widget-text-editor\" data-id=\"17e3256\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Each room at The Kropak Sidemen is named after these timeless textiles, celebrating the artistry and cultural heritage that continue to shape the soul of Bali.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-591aab2 e-flex e-con-boxed e-con e-parent\" data-id=\"591aab2\" data-element_type=\"container\" data-e-type=\"container\" id=\"culture\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d4e0e1 e-con-full e-flex e-con e-child\" data-id=\"7d4e0e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c2ef7 elementor-widget elementor-widget-heading\" data-id=\"a3c2ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A Living Culture<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b86f1c elementor-widget elementor-widget-text-editor\" data-id=\"5b86f1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Culture is woven into everyday life in Sidemen. Through meaningful experiences, guests are invited to discover local traditions, connect with the community, and celebrate the beauty of Bali\u2019s living heritage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24afc64 e-grid e-con-full zigzag-grid e-con e-child\" data-id=\"24afc64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-787f38c e-con-full e-flex e-con e-child\" data-id=\"787f38c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-688834c elementor-widget elementor-widget-heading\" data-id=\"688834c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sidemen Rice Field Walk<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ada0f0 elementor-widget elementor-widget-text-editor\" data-id=\"0ada0f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Stroll through the lush rice terraces and discover the peaceful rhythm of Sidemen\u2019s countryside<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cf777e e-con-full e-flex e-con e-child\" data-id=\"1cf777e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-7539fad elementor-widget elementor-widget-heading\" data-id=\"7539fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cycling Through Sidemen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c91e33 elementor-widget elementor-widget-text-editor\" data-id=\"3c91e33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Explore the cultural heart of Sidemen by ride through scenic village roads, rice fields, and hidden landscapes while embracing the beauty of Bali<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-747e17c e-con-full e-flex e-con e-child\" data-id=\"747e17c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-b9c8e2e elementor-widget elementor-widget-heading\" data-id=\"b9c8e2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Traditional Cooking Experience<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac860a8 elementor-widget elementor-widget-text-editor\" data-id=\"ac860a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Discover the authentic flavors of Bali through our cooking class, where you\u2019ll prepare traditional dishes using fresh local ingredients and time-honored recipes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6bd0988 e-con-full e-flex e-con e-child\" data-id=\"6bd0988\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-edb0567 elementor-widget elementor-widget-heading\" data-id=\"edb0567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Balinese Offering Making<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dbac42 elementor-widget elementor-widget-text-editor\" data-id=\"6dbac42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Learn the art of creating \u201ccanang sari\u201d, a daily Balinese offering that reflects gratitude, balance, and devotion<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf4b49f e-con-full e-flex e-con e-child\" data-id=\"bf4b49f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-91e2cab elementor-widget elementor-widget-heading\" data-id=\"91e2cab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Melukat Purification Ritual<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1979571 elementor-widget elementor-widget-text-editor\" data-id=\"1979571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Experience the sacred Balinese \u201cmelukat\u201d purification ritual, a traditional water blessing ceremony believed to cleanse the body, mind, and spirit<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b8504e e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"0b8504e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFFD1\" class=\"elementor-element elementor-element-0133e08 elementor-widget elementor-widget-heading\" data-id=\"0133e08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Guidede Meditation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8886491 elementor-widget elementor-widget-text-editor\" data-id=\"8886491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Find stillness and reconnect with yourself in the peaceful surroundings of Sidemen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c795fd e-flex e-con-boxed e-con e-parent\" data-id=\"4c795fd\" data-element_type=\"container\" data-e-type=\"container\" id=\"gallery\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-881bab5 e-con-full e-flex e-con e-child\" data-id=\"881bab5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44ca4da elementor-widget elementor-widget-heading\" data-id=\"44ca4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">cempala gallery<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-920697e elementor-widget elementor-widget-text-editor\" data-id=\"920697e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Culture is woven into everyday life in Sidemen. Through meaningful experiences, guests are invited to discover local traditions, connect with the community, and celebrate the beauty of Bali\u2019s living heritage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b8e6b1 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"5b8e6b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-335 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5b8e6b1\" data-elementor-lightbox-title=\"DVN00465 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAyOSwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA4XC9EVk4wMDQ2NS0xLndlYnAiLCJzbGlkZXNob3ciOiI1YjhlNmIxIn0%3D\" href='https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00465-1.webp'><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00465-1.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00465-1.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00465-1-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00465-1-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00465-1-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00465-1-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5b8e6b1\" data-elementor-lightbox-title=\"DVN00471 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAzMCwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA4XC9EVk4wMDQ3MS0xLndlYnAiLCJzbGlkZXNob3ciOiI1YjhlNmIxIn0%3D\" href='https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00471-1.webp'><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00471-1.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00471-1.webp 1620w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00471-1-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00471-1-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00471-1-768x512.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN00471-1-1536x1024.webp 1536w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5b8e6b1\" data-elementor-lightbox-title=\"DVN03448\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAzMiwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA4XC9EVk4wMzQ0OC53ZWJwIiwic2xpZGVzaG93IjoiNWI4ZTZiMSJ9\" href='https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03448.webp'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03448.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03448.webp 1080w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03448-300x200.webp 300w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03448-1024x683.webp 1024w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03448-768x512.webp 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5b8e6b1\" data-elementor-lightbox-title=\"DVN03560\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAzMywidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA4XC9EVk4wMzU2MC53ZWJwIiwic2xpZGVzaG93IjoiNWI4ZTZiMSJ9\" href='https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03560.webp'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1620\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03560.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03560.webp 1080w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03560-200x300.webp 200w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03560-683x1024.webp 683w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03560-768x1152.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03560-1024x1536.webp 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5b8e6b1\" data-elementor-lightbox-title=\"DVN03736\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAzNCwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA4XC9EVk4wMzczNi53ZWJwIiwic2xpZGVzaG93IjoiNWI4ZTZiMSJ9\" href='https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03736.webp'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1080\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03736.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03736.webp 720w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03736-200x300.webp 200w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03736-683x1024.webp 683w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5b8e6b1\" data-elementor-lightbox-title=\"DVN03770\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjAzNSwidXJsIjoiaHR0cHM6XC9cL3RoZWtyb3Bhay5jb21cL3NpZGVtZW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA4XC9EVk4wMzc3MC53ZWJwIiwic2xpZGVzaG93IjoiNWI4ZTZiMSJ9\" href='https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03770.webp'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1620\" src=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03770.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03770.webp 1080w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03770-200x300.webp 200w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03770-683x1024.webp 683w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03770-768x1152.webp 768w, https:\/\/thekropak.com\/sidemen\/wp-content\/uploads\/2026\/08\/DVN03770-1024x1536.webp 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Facilities where comfort meets nature Cempala kitchen Nestled within the peaceful surroundings of The Kropak Sidemen, Cempala Kitchen offers a dining experience inspired by the richness of Balinese flavors and the beauty of nature. We celebrate locally sourced ingredients, seasonal flavors, and traditional recipes with a contemporary touch. Every dining experience is designed to nourish [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-335","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/pages\/335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":325,"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/pages\/335\/revisions"}],"predecessor-version":[{"id":2062,"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/pages\/335\/revisions\/2062"}],"wp:attachment":[{"href":"https:\/\/thekropak.com\/sidemen\/wp-json\/wp\/v2\/media?parent=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}